{"id":19,"date":"2017-06-19T07:07:27","date_gmt":"2017-06-19T07:07:27","guid":{"rendered":"https:\/\/www.mosconestudio.it\/about\/"},"modified":"2021-02-01T19:57:29","modified_gmt":"2021-02-01T18:57:29","slug":"chi-siamo","status":"publish","type":"page","link":"https:\/\/www.mosconestudio.it\/en\/chi-siamo\/","title":{"rendered":"Who we are"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"19\" class=\"elementor elementor-19\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-15fed95 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"15fed95\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-04e577c\" data-id=\"04e577c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6a8efc elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"f6a8efc\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Who we are<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f83abc1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f83abc1\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-562e4c9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"562e4c9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c0ba305\" data-id=\"c0ba305\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e7bd92e elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"e7bd92e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><h4>The study with siege in Montiglio Monferrato deals with the design of costructions and the related works.<\/h4><h4>The activity began in 1970s, founded by the father  Surveyor Sergio Moscone, but since 2000 the sons Giuliano (civil engeneer) and Luciano (mechanical engeneer) exercise in associated form<\/h4><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a91724 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1a91724\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5283b60 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5283b60\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1c8d9d5\" data-id=\"1c8d9d5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23b064d elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"23b064d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Education and qualifications<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0328f58 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0328f58\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-808a997\" data-id=\"808a997\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-98dcb83 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"98dcb83\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b0b5a15\" data-id=\"b0b5a15\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58193d9 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"58193d9\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Eng. Giuliano Moscone<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e3cb7f9\" data-id=\"e3cb7f9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e5f75fd elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"e5f75fd\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInRight&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Eng. Luciano Moscone<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5bd3bd7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5bd3bd7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fc1e486\" data-id=\"fc1e486\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-907eaa6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"907eaa6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ba4013a\" data-id=\"ba4013a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ee8aed elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"6ee8aed\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><ul>\n \t<li>Diploma: Liceo Scientifico F. Vercelli (Asti)<\/li>\n \t<li>Degree: Civil engeneering (Politecnico di Torino)<\/li>\n<br \/>\n \t<li>Certificator in the field of fires preventing (D.M. 05\/08\/11)<\/li>\n \t<li>Coordinator for the security design-execution (D. Lgs. 81\/08)<\/li>\n \t<li>Tester for normal, prestressed and metal reinforced concrete works (Legge 1086\/71)<\/li>\n \t<li>Energetic certificator (L. R. 13\/07)<\/li>\n<\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b9ec592\" data-id=\"b9ec592\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-adfc80f elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"adfc80f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInRight&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><ul>\n \t<li>Diploma: Liceo Scientifico F. Vercelli (Asti)<\/li>\n \t<li>Degree: Mechanical engeneering (Politecnico di Torino)<\/li>\n<br\/>\n \t<li>Tester for normal, prestressed and metal reinforced concrete works (Legge 1086\/71)<\/li>\n \t<li>Energetic certificator (L. R. 13\/07)<\/li>\n \t<li>Energetic consulent CasaClima<\/li>\n<\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d49cbd6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d49cbd6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8688ee8\" data-id=\"8688ee8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ecec6c5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ecec6c5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ef6e72b\" data-id=\"ef6e72b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5c28f7a\" data-id=\"5c28f7a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df053ed elementor-invisible elementor-widget elementor-widget-image\" data-id=\"df053ed\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInRight&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.agenziacasaclima.it\/it\/moscone-luciano-ing--17-30341.html\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"270\" src=\"https:\/\/www.mosconestudio.it\/wp-content\/uploads\/2020\/07\/KlimaHaus_Berater_deit_RGB-300x270.jpg\" class=\"attachment-medium size-medium\" alt=\"Logo consulente CasaClima\" srcset=\"https:\/\/www.mosconestudio.it\/wp-content\/uploads\/2020\/07\/KlimaHaus_Berater_deit_RGB-300x270.jpg 300w, https:\/\/www.mosconestudio.it\/wp-content\/uploads\/2020\/07\/KlimaHaus_Berater_deit_RGB.jpg 709w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-faf3363 elementor-align-right elementor-hidden-phone elementor-invisible elementor-widget elementor-widget-button\" data-id=\"faf3363\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInRight&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/www.agenziacasaclima.it\/it\/moscone-luciano-ing--17-30341.html\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">CasaClima agency<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7cc734 elementor-widget elementor-widget-spacer\" data-id=\"f7cc734\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Chi siamo Lo studio Moscone con sede a Montiglio Monferrato si occupa della progettazione di costruzioni edili e delle relative pratiche accessorie. L&#8217;attivit\u00e0 \u00e8 iniziata negli anni &#8217;70 dal pap\u00e0 geom. Sergio Moscone, successivamente si sono inseriti i figli, prima Giuliano (ingegnere civile) e poi Luciano (ingegnere meccanico), che dal 2000 esercitano in forma associata. &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/www.mosconestudio.it\/en\/chi-siamo\/\"> <span class=\"screen-reader-text\">Who we are<\/span> Read More &raquo;<\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-19","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Chi siamo - Studio Tecnico Associato Moscone<\/title>\n<meta name=\"description\" content=\"Lo Studio Moscone a Montiglio Monferrato in provincia di Asti offre servizi nel campo dell&#039;edilizia, dalla progettazione urbanistica a quella di singoli edifici, residenziali e artigianali\/commerciali, con particolare attenzione alla sostenibilit\u00e0 e risparmio energetico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mosconestudio.it\/en\/chi-siamo\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chi siamo - Studio Tecnico Associato Moscone\" \/>\n<meta property=\"og:description\" content=\"Lo Studio Moscone a Montiglio Monferrato in provincia di Asti offre servizi nel campo dell&#039;edilizia, dalla progettazione urbanistica a quella di singoli edifici, residenziali e artigianali\/commerciali, con particolare attenzione alla sostenibilit\u00e0 e risparmio energetico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mosconestudio.it\/en\/chi-siamo\/\" \/>\n<meta property=\"og:site_name\" content=\"Studio Tecnico Associato Moscone\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-01T18:57:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mosconestudio.it\/wp-content\/uploads\/2020\/07\/KlimaHaus_Berater_deit_RGB-300x270.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.mosconestudio.it\/en\/#organization\",\"name\":\"Studio Tecnico Associato Moscone\",\"url\":\"https:\/\/www.mosconestudio.it\/en\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.mosconestudio.it\/en\/#logo\",\"inLanguage\":\"en-GB\",\"url\":\"https:\/\/www.mosconestudio.it\/wp-content\/uploads\/2020\/07\/LOGO-Model_Remake.jpg\",\"width\":1115,\"height\":1115,\"caption\":\"Studio Tecnico Associato Moscone\"},\"image\":{\"@id\":\"https:\/\/www.mosconestudio.it\/en\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mosconestudio.it\/en\/#website\",\"url\":\"https:\/\/www.mosconestudio.it\/en\/\",\"name\":\"Studio Tecnico Associato Moscone\",\"description\":\"Studio di progettazione civile\",\"publisher\":{\"@id\":\"https:\/\/www.mosconestudio.it\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.mosconestudio.it\/en\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.mosconestudio.it\/chi-siamo\/#primaryimage\",\"inLanguage\":\"en-GB\",\"url\":\"https:\/\/www.mosconestudio.it\/wp-content\/uploads\/2020\/07\/KlimaHaus_Berater_deit_RGB.jpg\",\"width\":709,\"height\":638,\"caption\":\"Logo consulente CasaClima\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mosconestudio.it\/chi-siamo\/#webpage\",\"url\":\"https:\/\/www.mosconestudio.it\/chi-siamo\/\",\"name\":\"Chi siamo - Studio Tecnico Associato Moscone\",\"isPartOf\":{\"@id\":\"https:\/\/www.mosconestudio.it\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.mosconestudio.it\/chi-siamo\/#primaryimage\"},\"datePublished\":\"2017-06-19T07:07:27+00:00\",\"dateModified\":\"2021-02-01T18:57:29+00:00\",\"description\":\"Lo Studio Moscone a Montiglio Monferrato in provincia di Asti offre servizi nel campo dell'edilizia, dalla progettazione urbanistica a quella di singoli edifici, residenziali e artigianali\/commerciali, con particolare attenzione alla sostenibilit\\u00e0 e risparmio energetico.\",\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mosconestudio.it\/chi-siamo\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.mosconestudio.it\/en\/wp-json\/wp\/v2\/pages\/19","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mosconestudio.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.mosconestudio.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.mosconestudio.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mosconestudio.it\/en\/wp-json\/wp\/v2\/comments?post=19"}],"version-history":[{"count":35,"href":"https:\/\/www.mosconestudio.it\/en\/wp-json\/wp\/v2\/pages\/19\/revisions"}],"predecessor-version":[{"id":1467,"href":"https:\/\/www.mosconestudio.it\/en\/wp-json\/wp\/v2\/pages\/19\/revisions\/1467"}],"wp:attachment":[{"href":"https:\/\/www.mosconestudio.it\/en\/wp-json\/wp\/v2\/media?parent=19"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}